{"id":4277,"date":"2026-09-02T14:50:46","date_gmt":"2026-09-02T12:50:46","guid":{"rendered":"https:\/\/www.cadooh.de\/?p=4277"},"modified":"2026-09-02T14:53:21","modified_gmt":"2026-09-02T12:53:21","slug":"die-sock-rock-bag-neue-haekelanleitung","status":"publish","type":"post","link":"https:\/\/www.cadooh.de\/index.php\/2026\/09\/02\/die-sock-rock-bag-neue-haekelanleitung\/","title":{"rendered":"die &#8222;SOCK ROCK BAG&#8220; &#8211; neue H\u00e4kelanleitung"},"content":{"rendered":"<p>Meine neue <strong>H\u00e4kelanleitung<\/strong>, die \ud83d\udc5c <strong>SOCK ROCK BAG \ud83d\udc5c<\/strong> \u00a0ist fast frisch ver\u00f6ffentlicht &#8230; <img decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/plugins\/wp-edit\/plugins\/emoticons\/img\/smiley-smile.gif\" \/><\/p>\n<p><!--more--><\/p>\n<p><img decoding=\"async\" class=\"emoji\" style=\"background-color: #ffffff;\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f4cc.svg\" alt=\"\ud83d\udccc\" \/> Du kannst das PDF bald bei mir im <strong>Shop bei <\/strong><strong>Crazypatterns<\/strong>\u00a0 &amp;\/oder bei der lieben Francis von <strong>MegaBobbel<\/strong>\u00a0mit derzeitigem Rabatt kaufen \u2026<br \/>\n<span style=\"color: #3366ff;\"><em>available in English &amp; German language<\/em><\/span><\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/0.jpg\" alt=\"\" width=\"350\" height=\"263\" \/><\/strong>(<em>Fotos teilweise Hintergr\u00fcnde mit KI-Inhalt<\/em>)<strong><br \/>\nOkay, Du fragst Dich jetzt, was ist die Tasche nun wirklich. Und warum jetzt ne Socke?<img decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/plugins\/wp-edit\/plugins\/emoticons\/img\/smiley-surprised.gif\" \/><\/strong><\/p>\n<p><strong>Design-Idee<\/strong>: eine Umh\u00e4ngetasche (<em>die man vielleicht auch als Body Cross Bag tragen kann<\/em>) in einem feschen Korbmuster (<em>Reliefst\u00e4bchen<\/em>), evtl. mit Innenfutter und Rei\u00dfverschluss. Das Ganze aus Sockenwolle geh\u00e4kelt.<\/p>\n<p><strong>CHALLENGE<\/strong>: die Tasche soll kaum N\u00e4hte haben. Am Besten in einem Rutsch geh\u00e4kelt. Schicke Metall-Accessoires sollen der Tasche einen hippen und modernen Look geben.<\/p>\n<p><strong>FERTIGES DESIGN<\/strong>: lange get\u00fcftelt, geh\u00e4kelt, aufgeribbelt, geh\u00e4kelt, aufgeribbelt, geh\u00e4kelt, getestet \u2026 Anleitung geschrieben, fotografiert, \u00fcbersetzt \u2026 da ist sie nun, ich pr\u00e4sentiere nach einem halben Jahr endlich die <strong>SOCK ROCK BAG\u00a0<\/strong><\/p>\n<hr \/>\n<p>Die fertige Tasche (<em>ohne Tr\u00e4ger<\/em>) ist ca. b\/h <strong>24 x 29 cm gro\u00df<\/strong> und <strong>besteht aus einer doppelf\u00e4digen Sockenwolle 4-fach<\/strong>. Es w\u00e4re also auch einf\u00e4dig eine Sockenwolle 8-fach m\u00f6glich. Und f\u00fcr Farbverl\u00e4ufe empfehle ich Modal Bobbelgarn.<\/p>\n<p><strong>TOLL: Das H\u00e4keln beginnt mit dem Boden, geht nahtlos zu den Taschenw\u00e4nden weiter und endet in kordelartigen Tr\u00e4gern, die individuell in der L\u00e4nge angepasst werden k\u00f6nnen. Und nur hier <\/strong>(<em>an den Seiten gibt es nur Abn\u00e4her<\/em>)<strong> befindet sich oben dann eine Naht. Also kein l\u00e4stiges Aneinandern\u00e4hen von schiefen Seitenteilen !!!<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/9b1f0bd2-41e1-4900-9763-37e5c7841b8d.png\" alt=\"\" width=\"350\" height=\"263\" \/><br \/>\n<\/strong>Ich habe mich f\u00fcr Modal-Garn entschieden, damit die Tasche eine f\u00fcllige, dicke Struktur bekommt.<br \/>\nGenau wie bei der Sockenwolle, wird das Garn doppelf\u00e4dig verarbeitet, hei\u00dft also bei der Bobbelwolle, h\u00e4kelst Du 2x 4f\u00e4dig, dadurch entstehen mittig attraktive melierte Farbverl\u00e4ufe, die dem Auge schmeicheln.<\/p>\n<p>Je mehr Baumwolle vorhanden ist, umso weicher wird nat\u00fcrlich die Tasche. Mein Favoritengarn war daher die Sockenwolle von Supergarne (<em>keine Werbung, keine Provision, nur die eigene \u00dcberzeugung!<\/em>) und Bobbelwolle von MegaBobbel mit Mondschein und Lavendelgl\u00fcck. Durch die Kooperation mit Francis gibt es bald supersch\u00f6ne Bobbel Sock Rock &#8211; Sets. Seid gespannt!<\/p>\n<p><strong>Durch den Doppelfaden sind viele Farbkompositionen m\u00f6glich. So kann ein Faden unifarben sein, der andere mit Farbverlauf.<\/strong><br \/>\n<strong>Eine Maschenprobe wird es Dir vereinfachen, die richtigen 2 Wollf\u00e4den zu finden.<\/strong><\/p>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>Hier mal ein paar Farbbeispiel-Impressionen<\/strong><\/span>:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/1a.jpg\" alt=\"\" width=\"350\" height=\"263\" \/><strong>Sockenwolle 4-fach<\/strong><br \/>\nMarke: Supergarne<br \/>\n<strong><br \/>\nSchwarze Bag links<\/strong>:<br \/>\nAktiv 4-fach Tweed, Col.: 52-99 tweed schwarz &amp;<br \/>\nAktiv 4-fach UNI, Col.: 25-99 schwarz<br \/>\n<strong>Gr\u00fcne Bag rechts<\/strong>:<br \/>\n2 x Aktiv 4-fach UNI, Col.: 25-76 moosgr\u00fcn<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/1.jpg\" alt=\"\" width=\"350\" height=\"263\" \/><br \/>\n<strong>Modal Bobbelwolle 4-f\u00e4dig<\/strong><br \/>\nMarke: MegaBobbel<br \/>\n<strong><br \/>\nLila-Bag links<\/strong>:<br \/>\n2 x Aubergine + 1 x Lavendelgl\u00fcck<br \/>\n&amp; eine kleine Extra-Prise SockRock<br \/>\n<strong>Blaue Bag rechts<\/strong>:<br \/>\n2 x Schatten + 1 x Mondschein<br \/>\n&amp; eine kleine Extra-Prise SockRock<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/1b.jpg\" alt=\"\" width=\"350\" height=\"263\" \/><\/p>\n<p><strong><br \/>\nTasche rot links<\/strong>:<br \/>\nSockenwolle + einem Mixgarn<br \/>\nMarke: <strong>Arwetta v. Filcolana<\/strong><br \/>\nCol.: 810, Chrysanthemum,<br \/>\n<span class=\"metafield-multi_line_text_field\">80% Superwash Merino | 20% Nylon,<br \/>\n<\/span>50 g \/ ca. 210 m LL<br \/>\n&amp; <strong>Lana Grossa Gomitolo<\/strong><br \/>\nCol.: 2014, BW\/Leinen\/Viskose,<br \/>\n100 g \/ ca. 290 m LL<br \/>\n(<em>das Garn wird wohl nicht mehr produziert<\/em>)<br \/>\n<strong><br \/>\nTasche in senfgelb oben rechts:<br \/>\n<\/strong><strong>Sockenwolle 4-fach Marke: Supergarne<br \/>\n<\/strong>2 x Aktiv 4-fach DIAMOND UNI, Col.: 320-23 gold<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/maiin-1.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/1b-1.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/629c037c-b572-4884-b586-cfe0f7fc03c4.png\" alt=\"\" width=\"500\" height=\"375\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/1-1.jpg\" alt=\"\" width=\"500\" height=\"500\" \/><\/p>\n<hr \/>\n<p>Sehr sch\u00f6n sieht die Bag aus, wenn man nat\u00fcrlich noch ein Innenfutter einn\u00e4ht. Jetzt noch eine N\u00e4hmaschine rauskramen und aufbauen, etc.?<br \/>\nIch habe zum Gl\u00fcck ein kleines Handmade-Tutorial gefunden und f\u00fcr die Tasche umgearbeitet, so dass alle meine h\u00fcbschen kleinen Bags nun ein Innenleben und einen sichernden Rei\u00dfverschluss haben. Falls Euch das gef\u00e4llt, schaut mal unter diesen <a href=\"https:\/\/www.cadooh.de\/index.php\/tutorials\/sock-rock-bag\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #3366ff;\"><strong>LINK<\/strong><\/span><\/a> nach.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/3b-1.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/18.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.cadooh.de\/wp-content\/uploads\/2026\/09\/8.jpg\" alt=\"\" width=\"343\" height=\"412\" \/>Sooo, hier habe ich ein wenig mit der KI gespielt<br \/>\nund sie wollte partout meine Bag nicht kleiner machen.<img decoding=\"async\" src=\"https:\/\/www.cadooh.de\/wp-content\/plugins\/wp-edit\/plugins\/emoticons\/img\/smiley-surprised.gif\" \/><br \/>\nIn Natur ist sie etwas kleiner und mehr Handtasche als Sack.<\/p>\n<p>Und ich w\u00fcnschte, ich h\u00e4tte auch solche \u00c4pfel zum Anbei\u00dfen im Garten h\u00e4ngen.<br \/>\nAber durch die D\u00fcrre sehen alle richtig l\u00fctt und traurig aus &#8230;<\/p>\n<p>Ich w\u00fcnsche Euch auf alle F\u00e4lle viel Freude mit der SOCK ROCK BAG!<br \/>\nIn jeder gekauften deutschen Anleitung\/PDF gibt&#8217;s auch ein kleines Goodie.<\/p>\n<p>Liebe Gr\u00fc\u00dfe<br \/>\nBirgit Luise<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meine neue H\u00e4kelanleitung, die \ud83d\udc5c SOCK ROCK BAG \ud83d\udc5c \u00a0ist fast frisch ver\u00f6ffentlicht &#8230;<\/p>\n","protected":false},"author":1,"featured_media":4278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[147,12,319,177,77,13,320,172,318,321],"class_list":["post-4277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-haekeln","tag-crazy-patterns","tag-crochet","tag-crochet-bag","tag-crochet-pattern","tag-haekelanleitung","tag-haekeln","tag-sock-rock-bag","tag-tasche","tag-tasche-haekeln","tag-umhaengetasche-haekeln"],"_links":{"self":[{"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/posts\/4277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/comments?post=4277"}],"version-history":[{"count":38,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/posts\/4277\/revisions"}],"predecessor-version":[{"id":4341,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/posts\/4277\/revisions\/4341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/media\/4278"}],"wp:attachment":[{"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/media?parent=4277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/categories?post=4277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadooh.de\/index.php\/wp-json\/wp\/v2\/tags?post=4277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}